{"id":89211,"date":"2022-09-30T08:37:55","date_gmt":"2022-09-30T11:37:55","guid":{"rendered":"https:\/\/radiosolaris.com.br\/beta\/?p=89211"},"modified":"2022-09-30T08:37:57","modified_gmt":"2022-09-30T11:37:57","slug":"justica-eleitoral-alerta-sobre-possivel-alteracao-em-local-de-votacao","status":"publish","type":"post","link":"https:\/\/radiosolaris.com.br\/beta\/justica-eleitoral-alerta-sobre-possivel-alteracao-em-local-de-votacao\/","title":{"rendered":"Justi\u00e7a Eleitoral alerta sobre poss\u00edvel altera\u00e7\u00e3o em local de vota\u00e7\u00e3o"},"content":{"rendered":"\n<h4 id=\"eleitor-deve-conferir-sua-secao-antes-de-sair-de-casa\" class=\"wp-block-heading\">Eleitor deve conferir sua se\u00e7\u00e3o antes de sair de casa<\/h4>\n\n\n\n<p>A maior parte dos Tribunais regionais eleitorais (TRE\u2019s) est\u00e3o alertando sobre altera\u00e7\u00f5es feitas nos locais de vota\u00e7\u00e3o e refor\u00e7ando a necessidade de que o eleitor confira a localiza\u00e7\u00e3o de sua se\u00e7\u00e3o&nbsp;antes de sair de casa, mesmo que sempre tenha votado no mesmo local.<img  decoding=\"async\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  class=\" pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1485218&amp;o=node\" ><img  decoding=\"async\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  class=\" pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1485218&amp;o=node\" ><\/p>\n\n\n\n<p>Na capital paulista, por exemplo, foi fechado o&nbsp;maior centro de vota\u00e7\u00e3o da cidade, o Centro Universit\u00e1rio Anhanguera, que atendia a 25 mil pessoas. Esses eleitores foram&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2022-09\/tre-sp-recomenda-consulta-antecipada-local-de-votacao\" target=\"_blank\" rel=\"noreferrer noopener\">redistribu\u00eddos<\/a>&nbsp;para tr\u00eas outros locais de vota\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>As mudan\u00e7as\u00a0ocorrem em todas as regi\u00f5es, de norte a sul do Brasil. Em Pernambuco, por exemplo, foram alterados 92 locais de vota\u00e7\u00e3o, enquanto em Santa Catarina 51 munic\u00edpios tiveram deslocamento de se\u00e7\u00f5es eleitorais para endere\u00e7os diferentes dos utilizados em pleitos anteriores.<\/p>\n\n\n\n<p>As mudan\u00e7as ocorrem devido a adequa\u00e7\u00f5es do contingente de eleitores e, \u00e0s vezes, por impedimentos estruturais, como reformas ou fechamento de estabelecimentos e pr\u00e9dios.<\/p>\n\n\n\n<h4 id=\"consulta-antecipada\" class=\"wp-block-heading\">Consulta antecipada<\/h4>\n\n\n\n<p>Para consultar o local de vota\u00e7\u00e3o com anteced\u00eancia, o eleitor tem v\u00e1rias op\u00e7\u00f5es. A verifica\u00e7\u00e3o pode ser feita no portal do TSE, na aba \u201cEleitor e Elei\u00e7\u00f5es\u201d, na parte superior da p\u00e1gina. Em seguida, deve-se clicar na op\u00e7\u00e3o \u201c<a href=\"https:\/\/www.tse.jus.br\/eleitor\/local-de-votacao-zonas-eleitorais\" target=\"_blank\" rel=\"noreferrer noopener\">Local de vota\u00e7\u00e3o\/zonas eleitorais<\/a>.&nbsp;<\/p>\n\n\n\n<p>Para pesquisar, basta preencher tr\u00eas informa\u00e7\u00f5es:<\/p>\n\n\n\n<p>\u2013 o nome, n\u00famero do t\u00edtulo de eleitor ou CPF;<\/p>\n\n\n\n<p>\u2013 data de nascimento;&nbsp;<\/p>\n\n\n\n<p>\u2013 nome da m\u00e3e.<\/p>\n\n\n\n<p>Feito isso, a p\u00e1gina indicar\u00e1 o resultado com o n\u00famero da zona eleitoral, da se\u00e7\u00e3o&nbsp;e o endere\u00e7o do local de vota\u00e7\u00e3o.<\/p>\n\n\n\n<h4 id=\"e-titulo\" class=\"wp-block-heading\">e-T\u00edtulo<\/h4>\n\n\n\n<p>Outra op\u00e7\u00e3o \u00e9 o aplicativo e-T\u00edtulo, que funciona como via digital do t\u00edtulo de eleitor. Pela ferramenta, que est\u00e1 dispon\u00edvel em vers\u00f5es para Android e iOS, basta fazer o&nbsp;<em>login<\/em>&nbsp;com suas informa\u00e7\u00f5es e, em seguida, ir em \u201cOnde votar\u201d. Uma nova tela se abrir\u00e1, com os dados sobre a se\u00e7\u00e3o, zona e o endere\u00e7o.<\/p>\n\n\n\n<p>Na maioria dos locais o aplicativo oferece ainda o servi\u00e7o de georreferenciamento, indicando em um mapa a localiza\u00e7\u00e3o da se\u00e7\u00e3o eleitoral.<\/p>\n\n\n\n<p>Vale lembrar que o aplicativo n\u00e3o poder\u00e1 ser baixado no dia da elei\u00e7\u00e3o, devendo ser instalado e configurado ao menos at\u00e9 o&nbsp;s\u00e1bado&nbsp;anterior ao pleito.<\/p>\n\n\n\n<h4 id=\"chatbot\" class=\"wp-block-heading\">Chatbot<\/h4>\n\n\n\n<p>Neste ano, o TSE criou, em parceria com o WhatsApp, um assistente virtual por meio do qual o eleitor pode perguntar onde fica seu local de vota\u00e7\u00e3o. Basta enviar um \u201coi\u201d para o n\u00famero&nbsp;<a href=\"+55 61 996371078\" target=\"_blank\" rel=\"noreferrer noopener\">+55 61 996371078<\/a>&nbsp;no WhatsApp ou clicar no&nbsp;<em>link<\/em>&nbsp;<a href=\"https:\/\/api.whatsapp.com\/send\/?phone=556196371078&amp;text&amp;type=phone_number&amp;app_absent=0\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/wa.me\/556196371078<\/a>&nbsp;e salvar o contato para receber os conte\u00fados do&nbsp;<em>bot<\/em>.<\/p>\n\n\n\n<p>A consulta ao local de vota\u00e7\u00e3o deve ser feita da seguinte forma: no menu principal, basta clicar em \u201cAcesse o Chatbot\u201d e, em seguida, \u201cver t\u00f3picos\u201d. Na sequ\u00eancia, dentro de \u201cServi\u00e7os ao Eleitor\u201d, basta escolher a op\u00e7\u00e3o \u201cLocal de vota\u00e7\u00e3o\u201d. A partir da\u00ed, a consulta pode ser feita pelo nome completo, t\u00edtulo de eleitor ou CPF.<\/p>\n\n\n\n<p>\u201cAo inserir qualquer um desses dados, juntamente com a data de nascimento e o nome completo da m\u00e3e, o aplicativo apresentar\u00e1 o resultado, com as informa\u00e7\u00f5es sobre o domic\u00edlio eleitoral \u2013 zona, se\u00e7\u00e3o, local, endere\u00e7o e munic\u00edpio \u2013 e com um mapa que indica, com precis\u00e3o, o local onde a eleitora e o eleitor devem comparecer para votar no dia\u00a02 de outubro, primeiro turno das Elei\u00e7\u00f5es 2022\u201d, explica o TSE.<\/p>\n\n\n\n<p>Fonte: Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eleitor deve conferir sua se\u00e7\u00e3o antes de sair de casa A maior parte dos Tribunais regionais eleitorais (TRE\u2019s) est\u00e3o alertando sobre altera\u00e7\u00f5es feitas nos locais de vota\u00e7\u00e3o e refor\u00e7ando a&hellip;<\/p>\n","protected":false},"author":21,"featured_media":89213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[84,14192],"tags":[3936,3133,14242],"powerkit_post_featured":[],"class_list":{"0":"post-89211","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brasil","8":"category-eleicoes","9":"tag-alteracao","10":"tag-justica-eleitoral","11":"tag-local-de-votacao"},"modified_by":"Ta\u00eds Vargas","_links":{"self":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/89211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/comments?post=89211"}],"version-history":[{"count":0,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/89211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media\/89213"}],"wp:attachment":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media?parent=89211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/categories?post=89211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/tags?post=89211"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/powerkit_post_featured?post=89211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}