{"id":86150,"date":"2022-08-16T14:31:07","date_gmt":"2022-08-16T17:31:07","guid":{"rendered":"https:\/\/radiosolaris.com.br\/beta\/?p=86150"},"modified":"2022-08-16T14:31:12","modified_gmt":"2022-08-16T17:31:12","slug":"confira-os-resultados-das-ultimas-blitzes-realizadas-em-sao-pelegrino-e-lourdes-em-caxias","status":"publish","type":"post","link":"https:\/\/radiosolaris.com.br\/beta\/confira-os-resultados-das-ultimas-blitzes-realizadas-em-sao-pelegrino-e-lourdes-em-caxias\/","title":{"rendered":"Confira os resultados das \u00faltimas blitzes realizadas em S\u00e3o Pelegrino e Lourdes, em Caxias"},"content":{"rendered":"\n<h4 id=\"ao-todo-41-condutores-foram-flagrados-dirigindo-embriagados-e-20-veiculos-foram-recolhidos\" class=\"wp-block-heading\">Ao todo, 41 condutores foram flagrados dirigindo embriagados e 20 ve\u00edculos foram recolhidos<\/h4>\n\n\n\n<p>Nos primeiros 15 dias do m\u00eas de agosto deste ano, as equipes da Fiscaliza\u00e7\u00e3o de Tr\u00e2nsito flagraram 41 condutores dirigindo sob efeito de bebidas alco\u00f3licas em Caxias do Sul. Foram realizadas duas blitzes da Opera\u00e7\u00e3o Balada Segura nos bairros S\u00e3o Pelegrino e Lourdes. Ao todo, os agentes abordaram 291 condutores e emitiram 105 multas.<\/p>\n\n\n\n<p>No somat\u00f3rio das duas opera\u00e7\u00f5es, 12 condutores foram flagrados dirigindo sem ter Carteira Nacional de Habilita\u00e7\u00e3o (CNH). Devido \u00e0s irregularidades, 20 ve\u00edculos foram removidos ao dep\u00f3sito credenciado do Detran\/RS.<\/p>\n\n\n\n<p>No decorrer da opera\u00e7\u00e3o, nove condutores fugiram do local ao avistarem os servidores, sendo quatro autom\u00f3veis e cinco motocicletas. Os agentes identificaram e multaram os condutores conforme regulamenta\u00e7\u00e3o prevista no C\u00f3digo de Tr\u00e2nsito Brasileiro (CTB).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  decoding=\"async\"  data-id=\"86151\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-86151 pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/08\/01-2-1024x690.jpg\" ><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1151\"  height=\"775\"  data-id=\"86152\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-86152 pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/08\/02-2.jpg\" ><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/08\/05.jpg\"><img  decoding=\"async\"  data-id=\"86153\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-86153 pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/08\/05-1024x673.jpg\" ><\/a><\/figure>\n<figcaption class=\"blocks-gallery-caption\">Fotos:  Fiscaliza\u00e7\u00e3o de Tr\u00e2nsito<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped\"> <figure class=\"wp-block-image size-large\"><figure class=\"wp-block-image size-large\"><\/figure> <figcaption class=\"blocks-gallery-caption\"><\/figure><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ao todo, 41 condutores foram flagrados dirigindo embriagados e 20 ve\u00edculos foram recolhidos Nos primeiros 15 dias do m\u00eas de agosto deste ano, as equipes da Fiscaliza\u00e7\u00e3o de Tr\u00e2nsito flagraram&hellip;<\/p>\n","protected":false},"author":17,"featured_media":86153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[83],"tags":[12660,1131,13306,148,11146,797,283],"powerkit_post_featured":[],"class_list":{"0":"post-86150","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-serra-gaucha","8":"tag-bairro-lourdes","9":"tag-blitz","10":"tag-blitz-em-caxias","11":"tag-caxias-do-sul","12":"tag-operacao-balada-segura","13":"tag-sao-pelegrino","14":"tag-serra-gaucha"},"modified_by":"Igor Panzenhagen","_links":{"self":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/86150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/comments?post=86150"}],"version-history":[{"count":0,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/86150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media\/86153"}],"wp:attachment":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media?parent=86150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/categories?post=86150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/tags?post=86150"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/powerkit_post_featured?post=86150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}