{"id":81040,"date":"2022-06-13T14:44:08","date_gmt":"2022-06-13T17:44:08","guid":{"rendered":"https:\/\/radiosolaris.com.br\/beta\/?p=81040"},"modified":"2022-06-13T14:44:16","modified_gmt":"2022-06-13T17:44:16","slug":"fiscalizacao-de-transito-autua-condutores-na-estacao-ferrea-em-caxias-do-sul","status":"publish","type":"post","link":"https:\/\/radiosolaris.com.br\/beta\/fiscalizacao-de-transito-autua-condutores-na-estacao-ferrea-em-caxias-do-sul\/","title":{"rendered":"Fiscaliza\u00e7\u00e3o de Tr\u00e2nsito autua condutores na Esta\u00e7\u00e3o F\u00e9rrea, em Caxias do Sul"},"content":{"rendered":"\n<h4 id=\"acao-aconteceu-na-noite-de-sabado-11-em-frente-a-casa-noturna-zero-54\" class=\"wp-block-heading\">A\u00e7\u00e3o aconteceu na noite de s\u00e1bado (11) em frente a casa noturna Zero 54<\/h4>\n\n\n\n<p>Na noite do \u00faltimo s\u00e1bado (11) e no in\u00edcio da manh\u00e3 de domingo (12), os servidores da Fiscaliza\u00e7\u00e3o de Tr\u00e2nsito promoveram uma nova edi\u00e7\u00e3o da Opera\u00e7\u00e3o Balada Segura em Caxias do Sul, com o objetivo principal de identificar poss\u00edveis condutores alcoolizados. A a\u00e7\u00e3o aconteceu na Esta\u00e7\u00e3o F\u00e9rrea, bairro S\u00e3o Pelegrino, em um trecho da Rua Dr. Augusto Pestana, em frente a casa noturna Zero 54.<\/p>\n\n\n\n<p>Entre 23h de s\u00e1bado e 2h de domingo, os agentes abordaram 18 condutores e emitiram 11 autos de infra\u00e7\u00e3o de tr\u00e2nsito. Tr\u00eas ve\u00edculos foram removidos ao dep\u00f3sito credenciado do Detran\/RS, e outros dois condutores foram autuados por se recusarem \u00e0 realiza\u00e7\u00e3o do teste do etil\u00f4metro ap\u00f3s pedido do servidor.<br><br>Vale destacar que se recusar a fazer o teste \u00e9 constitucional, por\u00e9m implica infra\u00e7\u00e3o grav\u00edssima. A medida administrativa prevista \u00e9 a suspens\u00e3o do direito de dirigir por 12 meses, al\u00e9m de multa no valor de R$ 2.934,70.<\/p>\n\n\n\n<p>Durante a opera\u00e7\u00e3o, os servidores tamb\u00e9m fiscalizaram o cumprimento da sinaliza\u00e7\u00e3o de proibi\u00e7\u00e3o de estacionamento na Rua Dr. Augusto Pestana, das 23h \u00e0s 6h.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"683\"  data-id=\"81048\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-81048 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/06\/IMG_1985-1-1024x683.jpg\"  data-pk-srcset=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/06\/IMG_1985-1-1024x683.jpg 1024w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/06\/IMG_1985-1-300x200.jpg 300w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/06\/IMG_1985-1-768x512.jpg 768w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/06\/IMG_1985-1.jpg 1280w\" ><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/06\/InkedIMG_2022_LI-scaled.jpg\"><img  decoding=\"async\"  data-id=\"81047\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-81047 pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/06\/InkedIMG_2022_LI-1024x683.jpg\" ><\/a><\/figure>\n<figcaption class=\"blocks-gallery-caption\"><br><\/figcaption><\/figure>\n\n\n\n<p>Fotos: Rodrigo Rossi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00e3o aconteceu na noite de s\u00e1bado (11) em frente a casa noturna Zero 54 Na noite do \u00faltimo s\u00e1bado (11) e no in\u00edcio da manh\u00e3 de domingo (12), os servidores&hellip;<\/p>\n","protected":false},"author":17,"featured_media":81047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[83],"tags":[1131,148,9613,2778,11146,283],"powerkit_post_featured":[],"class_list":{"0":"post-81040","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-serra-gaucha","8":"tag-blitz","9":"tag-caxias-do-sul","10":"tag-estacao-ferrea","11":"tag-fiscalizacao-de-transito","12":"tag-operacao-balada-segura","13":"tag-serra-gaucha"},"modified_by":"Igor Panzenhagen","_links":{"self":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/81040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/comments?post=81040"}],"version-history":[{"count":0,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/81040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media\/81047"}],"wp:attachment":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media?parent=81040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/categories?post=81040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/tags?post=81040"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/powerkit_post_featured?post=81040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}