{"id":79744,"date":"2022-05-27T13:31:12","date_gmt":"2022-05-27T16:31:12","guid":{"rendered":"https:\/\/radiosolaris.com.br\/beta\/?p=79744"},"modified":"2022-05-27T13:31:15","modified_gmt":"2022-05-27T16:31:15","slug":"prefeitura-anuncia-local-do-novo-canil-municipal-de-caxias-do-sul","status":"publish","type":"post","link":"https:\/\/radiosolaris.com.br\/beta\/prefeitura-anuncia-local-do-novo-canil-municipal-de-caxias-do-sul\/","title":{"rendered":"Prefeitura anuncia local do novo canil municipal de Caxias do Sul"},"content":{"rendered":"\n<h4 id=\"area-localizada-na-linha-luciana-nao-constava-na-consulta-popular-realizada-pela-administracao-em-marco\" class=\"wp-block-heading\">\u00c1rea localizada na Linha Luciana, n\u00e3o constava na consulta popular realizada pela administra\u00e7\u00e3o em mar\u00e7o<\/h4>\n\n\n\n<p>A Prefeitura de Caxias do Sul divulgou na manh\u00e3 desta sexta-feira (27), o local escolhido para constru\u00e7\u00e3o do novo canil municipal e do Parque de Prote\u00e7\u00e3o Animal. A \u00e1rea de 50 mil metros quadrados do canil, fica localizada na Linha Luciana, Col\u00f4nia Sertorina, h\u00e1 cerca de um quil\u00f4metro da Esta\u00e7\u00e3o de Tratamento Samuara, do Servi\u00e7o Aut\u00f4nomo Municipal de \u00c1gua e Esgoto (Samae). Outra \u00e1rea anexa, ao lado do terreno do canil, deve ser alugada em um primeiro momento para a constru\u00e7\u00e3o do parque. &nbsp;&nbsp;<\/p>\n\n\n\n<p>De acordo com o secret\u00e1rio Municipal de Meio Ambiente, Jo\u00e3o Os\u00f3rio Martins, a \u00e1rea apontada \u00e9 a mais pr\u00f3xima do per\u00edmetro urbano de Caxias, entre as que estavam sendo analisadas. Al\u00e9m disso, ficou acertada uma permuta \u2013 que n\u00e3o deve onerar os cofres p\u00fablicos \u2013 para a aquisi\u00e7\u00e3o do terreno. De acordo com a prefeitura, a permuta com o propriet\u00e1rio das terras envolve a troca por um outro local, de 2 hectares, no bairro Santa L\u00facia, e que n\u00e3o estava sendo utilizado.<\/p>\n\n\n\n<p>O terreno escolhido pela administra\u00e7\u00e3o n\u00e3o constava na lista da consulta popular realizada para que a comunidade pudesse avaliar as \u00e1reas dispon\u00edveis para sediar o canil. Na consulta, realizada entre os dias 28 e 31 de mar\u00e7o, constavam tr\u00eas locais: em S\u00e3o Virg\u00edlio da 2\u00aa L\u00e9gua, na regi\u00e3o de Forqueta; no bairro S\u00e3o Victor Cohab; e na localidade S\u00e3o Victor e Corona, perto de Gal\u00f3polis. Apesar da decis\u00e3o da Prefeitura pela quarta \u00e1rea, outras respostas obtidas na consulta, serviram de subs\u00eddio para a escolha, entre as quais, a proximidade do canil com o per\u00edmetro urbano. &nbsp;<\/p>\n\n\n\n<p>A partir de agora, o prefeito Adil\u00f3 Didomenico (PSDB) deve protocolar na C\u00e2mara de Vereadores um projeto com os detalhes que envolvem a negocia\u00e7\u00e3o da permuta. No legislativo, os vereadores devem analisar e votar o projeto. Se aprovado \u2013 destaca ainda Adil\u00f3 \u2013, o terreno passa para a administra\u00e7\u00e3o p\u00fablica, que deve iniciar o segundo projeto, visando os detalhes da constru\u00e7\u00e3o do espa\u00e7o do canil. No local, deve ser erguida a estrutura para abrigar c\u00e3es, gatos e, se necess\u00e1rio, receber momentaneamente outros animais tamb\u00e9m.<\/p>\n\n\n\n<p>O secretario Martins destacou afirmou que as obras ainda n\u00e3o t\u00eam previs\u00e3o de in\u00edcio, pois tudo depende da aprova\u00e7\u00e3o da permuta por parte dos vereadores. Por outro lado, a Secretaria j\u00e1 est\u00e1 em contato com um empres\u00e1rio interessado em adquirir a \u00e1rea do atual canil de Caxias, localizado na localidade de S\u00e3o Virg\u00edlio. A ideia, explica o secret\u00e1rio, \u00e9 realizar uma nova permuta, entregando o controle do antigo terreno para a empresa, em troca da constru\u00e7\u00e3o do novo canil \u2013 conforme projeto aprovado pela prefeitura.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/05\/Prefeitura-de-Caxias-do-Sul-anuncia-local-do-novo-canil-municipal-1.jpeg\"><img  decoding=\"async\"  data-id=\"79747\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-79747 pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/05\/Prefeitura-de-Caxias-do-Sul-anuncia-local-do-novo-canil-municipal-1-1024x768.jpeg\" ><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/05\/Prefeitura-de-Caxias-do-Sul-anuncia-local-do-novo-canil-municipal-3.jpeg\"><img  decoding=\"async\"  data-id=\"79746\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-79746 pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/05\/Prefeitura-de-Caxias-do-Sul-anuncia-local-do-novo-canil-municipal-3-1024x768.jpeg\" ><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/05\/Prefeitura-de-Caxias-do-Sul-anuncia-local-do-novo-canil-municipal-2.jpeg\"><img  decoding=\"async\"  data-id=\"79745\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-79745 pk-lazyload\"  data-pk-sizes=\"auto\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2022\/05\/Prefeitura-de-Caxias-do-Sul-anuncia-local-do-novo-canil-municipal-2-1024x768.jpeg\" ><\/a><\/figure>\n<figcaption class=\"blocks-gallery-caption\">Fotos: Filipe Brogliatto\/ Grupo Solaris<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1rea localizada na Linha Luciana, n\u00e3o constava na consulta popular realizada pela administra\u00e7\u00e3o em mar\u00e7o A Prefeitura de Caxias do Sul divulgou na manh\u00e3 desta sexta-feira (27), o local escolhido&hellip;<\/p>\n","protected":false},"author":13,"featured_media":79745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[83],"tags":[5414,7805,148,5389,11658,11656,5578,11657,283],"powerkit_post_featured":[],"class_list":{"0":"post-79744","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-serra-gaucha","8":"tag-adilo-didomenico","9":"tag-canil-municipal","10":"tag-caxias-do-sul","11":"tag-coletiva-de-imprensa","12":"tag-joao-osorio-martins","13":"tag-parque-de-protecao-animal","14":"tag-prefeitura-de-caxias-do-sul","15":"tag-secretaria-municipal-de-meio-ambiente","16":"tag-serra-gaucha"},"modified_by":"Filipe Brogliatto","_links":{"self":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/79744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/comments?post=79744"}],"version-history":[{"count":0,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/79744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media\/79745"}],"wp:attachment":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media?parent=79744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/categories?post=79744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/tags?post=79744"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/powerkit_post_featured?post=79744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}