{"id":65660,"date":"2021-11-22T18:18:16","date_gmt":"2021-11-22T21:18:16","guid":{"rendered":"https:\/\/radiosolaris.com.br\/beta\/?p=65660"},"modified":"2021-11-22T18:27:20","modified_gmt":"2021-11-22T21:27:20","slug":"documentario-retrata-a-historia-das-vindimas-da-cancao-popular-de-flores-da-cunha","status":"publish","type":"post","link":"https:\/\/radiosolaris.com.br\/beta\/documentario-retrata-a-historia-das-vindimas-da-cancao-popular-de-flores-da-cunha\/","title":{"rendered":"Document\u00e1rio retrata a hist\u00f3ria das Vindimas da Can\u00e7\u00e3o Popular de Flores da Cunha"},"content":{"rendered":"\n<h4 id=\"exibicao-ocorre-dentro-da-programacao-da-semana-das-letras\" class=\"wp-block-heading\">Exibi\u00e7\u00e3o ocorre dentro da programa\u00e7\u00e3o da \u201cSemana das Letras\u201d<\/h4>\n\n\n\n<p>A partir desta segunda-feira (22), Flores da Cunha pode acompanhar e usufruir das atividades da \u201cSemana das Letras\u201d, promovida pela Secretaria de Educa\u00e7\u00e3o, Cultura e Desporto de Flores da Cunha. Com uma programa\u00e7\u00e3o recheada de atividades em escolas da rede municipal e estadual, a comunidade vai poder tamb\u00e9m, assistir o document\u00e1rio, \u201cA terra do galo que canta: as vindimas da can\u00e7\u00e3o popular de Flores da Cunha\u201d.<br><br>A exibi\u00e7\u00e3o ocorre nesta sexta-feira (26), na Casa de Cultura Fl\u00e1vio Luis Ferrarini, \u00e0s 19h30, sendo aberto ao p\u00fablico em geral e gratuito. Atendendo aos protocolos sanit\u00e1rios da Covid-19, as vagas para essa atividade s\u00e3o limitadas.<br>A produ\u00e7\u00e3o foi organizada a partir da pesquisa de conclus\u00e3o do mestrado em Hist\u00f3ria (UCS), da professora e historiadora Ta\u00edsa Verdi. A capta\u00e7\u00e3o de imagem \u00e9 de Leandro Foscarini, capta\u00e7\u00e3o de \u00e1udio Ricardo Mabilia. Foram entrevistadas algumas personalidades da cidade.<br><br>De 25 de novembro a 3 de dezembro, a Livraria Almanaque Cultural oferecer\u00e1 descontos nas compras de livros de 15% \u00e0 vista e 10% no prazo para 30 dias. As pessoas que visitarem a Casa de Cultura durante a semana e realizarem postagens nas redes sociais marcando os perfis Cultura em Flores e Almanaque Cultural concorrer\u00e3o a quatro vales-livros no valor de R$ 50 cada.<br><br>A professora e historiadora Ta\u00edsa Verdi, ressalta a import\u00e2ncia de se ter um document\u00e1rio que possa servir de par\u00e2metro e tamb\u00e9m fonte de pesquisa para alunos e estudantes no futuro. \u201cEsperamos que esse trabalho sirva como fonte de pesquisa para vindouros; que venham a complement\u00e1-lo, question\u00e1-lo \u2013 porque essa \u00e9 a fun\u00e7\u00e3o da Hist\u00f3ria. Al\u00e9m disso, o document\u00e1rio pode ser plenamente usado para fins did\u00e1ticos, uma vez que conectamos a nossa hist\u00f3ria local com a regional e nacional, com a \u00e9poca dos grandes festivais televisivos e mesmo com as quest\u00f5es pol\u00edticas, culturais e sociais do contexto da Ditadura Civil-Militar no Brasil,\u201d conclui a professora Ta\u00edsa.<\/p>\n\n\n\n<p>Texto: Bernardo Barcellos<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-22-at-17.15.36-1.jpeg\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"768\"  height=\"1024\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  data-id=\"65661\"  data-full-url=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-22-at-17.15.36-1.jpeg\"  data-link=\"https:\/\/radiosolaris.com.br\/beta\/?attachment_id=65661\"  class=\"wp-image-65661 pk-lazyload\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 768px) 100vw, 768px\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-22-at-17.15.36-1-768x1024.jpeg\"  data-pk-srcset=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-22-at-17.15.36-1-768x1024.jpeg 768w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-22-at-17.15.36-1-800x1067.jpeg 800w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-22-at-17.15.36-1.jpeg 960w\" ><\/a><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Exibi\u00e7\u00e3o ocorre dentro da programa\u00e7\u00e3o da \u201cSemana das Letras\u201d A partir desta segunda-feira (22), Flores da Cunha pode acompanhar e usufruir das atividades da \u201cSemana das Letras\u201d, promovida pela Secretaria&hellip;<\/p>\n","protected":false},"author":17,"featured_media":65663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[83],"tags":[9006,2535,1175,9007,2583,9005],"powerkit_post_featured":[],"class_list":{"0":"post-65660","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-serra-gaucha","8":"tag-a-terra-do-galo-que-canta","9":"tag-casa-da-cultura","10":"tag-documentario","11":"tag-semana-das-letras","12":"tag-vindima","13":"tag-vindimas-da-cancao-popular"},"modified_by":"Igor Panzenhagen","_links":{"self":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/65660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/comments?post=65660"}],"version-history":[{"count":0,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/65660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media\/65663"}],"wp:attachment":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media?parent=65660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/categories?post=65660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/tags?post=65660"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/powerkit_post_featured?post=65660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}