{"id":48804,"date":"2021-02-28T14:40:55","date_gmt":"2021-02-28T17:40:55","guid":{"rendered":"https:\/\/radiosolaris.com.br\/beta\/?p=48804"},"modified":"2021-02-28T14:40:59","modified_gmt":"2021-02-28T17:40:59","slug":"operacao-te-cuida-rs-dispersa-aglomeracoes-encerra-festas-clandestinas-e-orienta-populacao-sobre-a-bandeira-preta","status":"publish","type":"post","link":"https:\/\/radiosolaris.com.br\/beta\/operacao-te-cuida-rs-dispersa-aglomeracoes-encerra-festas-clandestinas-e-orienta-populacao-sobre-a-bandeira-preta\/","title":{"rendered":"Opera\u00e7\u00e3o Te Cuida RS dispersa aglomera\u00e7\u00f5es, encerra festas clandestinas e orienta popula\u00e7\u00e3o sobre a bandeira preta"},"content":{"rendered":"\n<h4 id=\"normalmente-utilizada-para-indicar-local-perigoso-para-banho-bandeira-preta-foi-hasteada-a-beira-mar-para-coibir-aglomeracoes\" class=\"wp-block-heading\">Normalmente utilizada para indicar local perigoso para banho, bandeira preta foi hasteada \u00e0 beira-mar para coibir aglomera\u00e7\u00f5es<\/h4>\n\n\n\n<p>Com equipes espalhadas por todo o Rio Grande do Sul, a Opera\u00e7\u00e3o Te Cuida RS realizou 359 fiscaliza\u00e7\u00f5es de estabelecimentos entre a noite de sexta-feira (26) e a madrugada de s\u00e1bado (27) para verificar o cumprimento da suspens\u00e3o de atividades n\u00e3o essenciais entre 20h e 5h. A a\u00e7\u00e3o integrada, com participa\u00e7\u00e3o de todas as institui\u00e7\u00f5es vinculadas \u00e0 Secretaria da Seguran\u00e7a P\u00fablica e \u00f3rg\u00e3os de vigil\u00e2ncia municipais, tamb\u00e9m fiscalizou o cumprimento dos protocolos da bandeira preta, vigente em todo o Estado at\u00e9, pelo menos, 7 de mar\u00e7o.<\/p>\n\n\n\n<p>Conforme dados da Brigada Militar (BM), foram recebidas 185 den\u00fancias de descumprimento das normas preventivas contra o coronav\u00edrus, das quais 61 acabaram confirmadas pela corpora\u00e7\u00e3o. Em 34 casos, foi preciso registrar boletim de atendimento ou termo circunstanciado para fechamento de estabelecimentos abertos ap\u00f3s o hor\u00e1rio determinado. Houve ainda 50 registros de ocorr\u00eancia para dispers\u00e3o de aglomera\u00e7\u00f5es e sete festas clandestinas foram encerradas.<\/p>\n\n\n\n<p>Em Santa Maria, a a\u00e7\u00e3o integrada com \u00f3rg\u00e3os municipais de fiscaliza\u00e7\u00e3o p\u00f4s fim a uma festa clandestina com cerca de 30 pessoas. Em S\u00e3o Louren\u00e7o do Sul, foi encerrada outra festa, com cerca de 20 pessoas, todas sem m\u00e1scara. Um rev\u00f3lver 38 foi apreendido com um jovem, que acabou preso em flagrante junto com a respons\u00e1vel pela organiza\u00e7\u00e3o do evento. No local, a pol\u00edcia ainda recolheu 1kg de coca\u00edna. Em todo o RS, as a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o da Opera\u00e7\u00e3o Te Cuida RS resultaram em 18 pris\u00f5es em flagrante, por diversos delitos.<\/p>\n\n\n\n<p>A maior parte das fiscaliza\u00e7\u00f5es de estabelecimentos se concentrou no Litoral Norte. As a\u00e7\u00f5es ocorreram em Cap\u00e3o da Canoa, Xangri-l\u00e1, Tramanda\u00ed, Imb\u00e9, Arroio do Sal, Torres, Os\u00f3rio, Santo Ant\u00f4nio da Patrulha e Tavares. Participaram efetivos da BM, Pol\u00edcia Civil, Instituto-Geral de Per\u00edcias (IGP), Corpo de Bombeiros Militar (CBMRS), Departamento Estadual de Tr\u00e2nsito (DetranRS) e \u00f3rg\u00e3os de vigil\u00e2ncia municipais. No total, 119 estabelecimentos comerciais foram vistoriados, sendo que desses 19 estavam abertos al\u00e9m do hor\u00e1rio permitido, com 121 clientes. Em todo o Estado, a BM contabilizou a abordagem de mais de 1,2 mil pessoas para orienta\u00e7\u00e3o das medidas preventivas.<\/p>\n\n\n\n<p>No s\u00e1bado, as praias de todo o litoral ga\u00facho amanheceram com bandeiras pretas nas guaritas de guarda-vidas e na faixa de areia, instaladas pelos bombeiros. A sinaliza\u00e7\u00e3o, normalmente utilizada para indicar o risco de morte em determinados pontos do mar, passou a indicar a proibi\u00e7\u00e3o de perman\u00eancia na faixa de areia, em dunas e no cal\u00e7ad\u00e3o das orlas, conforme determinam os protocolos da bandeira preta no modelo de Distanciamento Controlado.<\/p>\n\n\n\n<p>Apenas caminhadas e a pr\u00e1tica de exerc\u00edcios est\u00e3o permitidos. O banho de mar, por per\u00edodo n\u00e3o prolongado, tamb\u00e9m est\u00e1 liberado, mas n\u00e3o \u00e9 recomendado porque obriga os guarda-vidas a abandonarem a atividade de orienta\u00e7\u00e3o na praia para monitorar banhistas na \u00e1gua.<\/p>\n\n\n\n<p>As a\u00e7\u00f5es da Opera\u00e7\u00e3o Te Cuida RS ter\u00e3o continuidade durante todo o fim de semana, e as for\u00e7as de seguran\u00e7a refor\u00e7am o apelo \u00e0 popula\u00e7\u00e3o para que n\u00e3o participe de aglomera\u00e7\u00f5es e s\u00f3 fa\u00e7a deslocamentos quando for estritamente necess\u00e1rio. Os telefones para den\u00fancia de descumprimento das regras da bandeira preta s\u00e3o o 190 da BM e o 197 da Pol\u00edcia Civil.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img  loading=\"lazy\"  decoding=\"async\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABAQMAAAAl21bKAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAApJREFUCNdjYAAAAAIAAeIhvDMAAAAASUVORK5CYII=\"  alt=\"\"  class=\"wp-image-48805 pk-lazyload\"  width=\"438\"  height=\"246\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 438px) 100vw, 438px\"  data-pk-src=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/02\/TE-C.jpg\"  data-pk-srcset=\"https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/02\/TE-C.jpg 800w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/02\/TE-C-120x68.jpg 120w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/02\/TE-C-90x51.jpg 90w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/02\/TE-C-320x180.jpg 320w, https:\/\/radiosolaris.com.br\/beta\/wp-content\/uploads\/2021\/02\/TE-C-560x315.jpg 560w\" ><\/figure><\/div>\n\n\n\n<p>Fonte: Governo do RS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Normalmente utilizada para indicar local perigoso para banho, bandeira preta foi hasteada \u00e0 beira-mar para coibir aglomera\u00e7\u00f5es Com equipes espalhadas por todo o Rio Grande do Sul, a Opera\u00e7\u00e3o Te&hellip;<\/p>\n","protected":false},"author":1,"featured_media":48805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[93],"tags":[4437,5528,6222,227,197],"powerkit_post_featured":[],"class_list":{"0":"post-48804","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-rs","8":"tag-aglomeracoes","9":"tag-bandeira-preta","10":"tag-festas-clandestinas","11":"tag-operacao","12":"tag-rs"},"modified_by":null,"_links":{"self":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/48804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/comments?post=48804"}],"version-history":[{"count":0,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/posts\/48804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media\/48805"}],"wp:attachment":[{"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/media?parent=48804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/categories?post=48804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/tags?post=48804"},{"taxonomy":"powerkit_post_featured","embeddable":true,"href":"https:\/\/radiosolaris.com.br\/beta\/wp-json\/wp\/v2\/powerkit_post_featured?post=48804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}